{"id":24,"count":12,"description":"","link":"https:\/\/programasdesanfermin.com\/en\/product-category\/programas-san-fermin\/","name":"Programas San Ferm\u00edn","slug":"programas-san-fermin","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"ck9MPk1Sf8vOiBecp67Ms6S_OThwVkDxlA2p-84IAOM\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/programasdesanfermin.com\/en\/product-category\/programas-san-fermin\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/24\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/tienda\\\/#listItem\",\"name\":\"Nuestro cat\\u00e1logo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"Nuestro cat\\u00e1logo\",\"item\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/product-category\\\/programas-san-fermin\\\/#listItem\",\"name\":\"Programas San Ferm\\u00edn\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/product-category\\\/programas-san-fermin\\\/#listItem\",\"position\":3,\"name\":\"Programas San Ferm\\u00edn\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/tienda\\\/#listItem\",\"name\":\"Nuestro cat\\u00e1logo\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/24\\\/#collectionpage\",\"url\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/24\\\/\",\"name\":\"Programas San Ferm\\u00edn - PROGRAMAS DE LAS FIESTAS DE SAN FERM\\u00cdN DE PAMPLONA\\\/IRU\\u00d1EA\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/24\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/#organization\",\"name\":\"PROGRAMAS DE LAS FIESTAS DE SAN FERM\\u00cdN DE PAMPLONA\\\/IRU\\u00d1EA Fistas de San Fermin de Pamplona\",\"description\":\"SAN FERMIN Coleccionismo de programas de las fiestas de san fermin de pamplona Collecting programs from the San Fermin festivities in Pamplona\",\"url\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/\",\"email\":\"info@programasdesanfermin.com\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/programasdesanfermin.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/CARAVINAGRE.png\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/24\\\/#organizationLogo\",\"width\":493,\"height\":669},\"image\":{\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/24\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/\",\"name\":\"PROGRAMAS DE LAS FIESTAS DE SAN FERM\\u00cdN DE PAMPLONA\\\/IRU\\u00d1EA\",\"alternateName\":\"San Fermin Programs\",\"description\":\"SAN FERMIN\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/programasdesanfermin.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Programas San Ferm\u00edn - PROGRAMAS DE LAS FIESTAS DE SAN FERM\u00cdN DE PAMPLONA\/IRU\u00d1EA","description":"","canonical_url":"https:\/\/programasdesanfermin.com\/en\/product-category\/programas-san-fermin\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"ck9MPk1Sf8vOiBecp67Ms6S_OThwVkDxlA2p-84IAOM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/product_cat\/24\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/programasdesanfermin.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/programasdesanfermin.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/programasdesanfermin.com\/en\/tienda\/#listItem","name":"Nuestro cat\u00e1logo"}},{"@type":"ListItem","@id":"https:\/\/programasdesanfermin.com\/en\/tienda\/#listItem","position":2,"name":"Nuestro cat\u00e1logo","item":"https:\/\/programasdesanfermin.com\/en\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/programasdesanfermin.com\/en\/product-category\/programas-san-fermin\/#listItem","name":"Programas San Ferm\u00edn"},"previousItem":{"@type":"ListItem","@id":"https:\/\/programasdesanfermin.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/programasdesanfermin.com\/en\/product-category\/programas-san-fermin\/#listItem","position":3,"name":"Programas San Ferm\u00edn","previousItem":{"@type":"ListItem","@id":"https:\/\/programasdesanfermin.com\/en\/tienda\/#listItem","name":"Nuestro cat\u00e1logo"}}]},{"@type":"CollectionPage","@id":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/product_cat\/24\/#collectionpage","url":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/product_cat\/24\/","name":"Programas San Ferm\u00edn - PROGRAMAS DE LAS FIESTAS DE SAN FERM\u00cdN DE PAMPLONA\/IRU\u00d1EA","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/programasdesanfermin.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/product_cat\/24\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/programasdesanfermin.com\/en\/#organization","name":"PROGRAMAS DE LAS FIESTAS DE SAN FERM\u00cdN DE PAMPLONA\/IRU\u00d1EA Fistas de San Fermin de Pamplona","description":"SAN FERMIN Coleccionismo de programas de las fiestas de san fermin de pamplona Collecting programs from the San Fermin festivities in Pamplona","url":"https:\/\/programasdesanfermin.com\/en\/","email":"info@programasdesanfermin.com","logo":{"@type":"ImageObject","url":"https:\/\/programasdesanfermin.com\/wp-content\/uploads\/2024\/12\/CARAVINAGRE.png","@id":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/product_cat\/24\/#organizationLogo","width":493,"height":669},"image":{"@id":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/product_cat\/24\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/programasdesanfermin.com\/en\/#website","url":"https:\/\/programasdesanfermin.com\/en\/","name":"PROGRAMAS DE LAS FIESTAS DE SAN FERM\u00cdN DE PAMPLONA\/IRU\u00d1EA","alternateName":"San Fermin Programs","description":"SAN FERMIN","inLanguage":"en-US","publisher":{"@id":"https:\/\/programasdesanfermin.com\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/programasdesanfermin.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/programasdesanfermin.com\/en\/tienda\/\" title=\"Nuestro cat\u00e1logo\">Nuestro cat\u00e1logo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tProgramas San Ferm\u00edn\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/programasdesanfermin.com\/en"},{"label":"Nuestro cat\u00e1logo","link":"https:\/\/programasdesanfermin.com\/en\/tienda\/"},{"label":"Programas San Ferm\u00edn","link":"https:\/\/programasdesanfermin.com\/en\/product-category\/programas-san-fermin\/"}],"_links":{"self":[{"href":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/product_cat\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/programasdesanfermin.com\/en\/wp-json\/wp\/v2\/product?product_cat=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}